{"id":6277,"date":"2009-02-28T00:00:00","date_gmt":"2009-02-28T00:00:00","guid":{"rendered":"https:\/\/cecubogroup.com\/?p=6277"},"modified":"2021-04-05T16:47:18","modified_gmt":"2021-04-05T16:47:18","slug":"final-de-campana","status":"publish","type":"post","link":"https:\/\/www.cecubogroup.com\/pt\/blog\/final-de-campana\/","title":{"rendered":"Fim da campanha"},"content":{"rendered":"<p>\u00c0 parte as explos\u00f5es de Baltar em Orense, com ataques pessoais e directos a Anxo Quintana e ao atual Ministro Regional do Meio Ambiente, Francisco V\u00e1zquez, o \u00faltimo dia de campanha decorreu como esperado - como referi no post de quinta-feira -. Zapatero e Rajoy acabaram por personalizar a campanha nas suas figuras de forma absoluta; algo que, logicamente, n\u00e3o agradou nem a Touri\u00f1o nem a Feijoo.<\/p>\n<p>A Touri\u00f1o, porque, como dizia Anxo Lugilde em <a href=\"http:\/\/www.galiciae.com\/nova\/26027.html\" style=\"margin: 0px; padding: 0px; border: 0px; vertical-align: baseline; outline: none; color: rgb(51, 51, 51); text-decoration-line: none;\">o vosso artigo de ontem<\/a>Zapatero acabou por ganhar uma batalha que se arrastava desde 2004, quando o atual presidente da Xunta atribuiu o grande resultado de ZP na Galiza \u00e0 sua grande lideran\u00e7a do PSdG. Finalmente, perante o toque de corneta de Jos\u00e9 Blanco na \u00faltima semana, quando as sondagens mostravam o PPdG em ascens\u00e3o, trouxeram o presidente do governo para encerrar a campanha em Santiago, procurando mobilizar a base socialista perante a amea\u00e7a de uma escandalosa absten\u00e7\u00e3o.<\/p>\n<p>\nPor seu lado, \u00e9 preciso dizer que Rajoy n\u00e3o esperou por Feijoo para dar in\u00edcio ao \u00faltimo com\u00edcio da campanha. Uma reuni\u00e3o em que tamb\u00e9m participou Baltar, que interveio duas vezes devido ao atraso do candidato do PP \u00e0 presid\u00eancia da Xunta. O l\u00edder do PP em Ourense deve ser mencionado, porque \u00e9 um caso especial. Passou dois dias a criar uma pol\u00e9mica que n\u00e3o creio que tenha sido muito ben\u00e9fica para o seu partido (embora alguns acreditem que se tratou de uma divis\u00e3o de pap\u00e9is); mas, al\u00e9m disso, ganhou o jogo contra Feijoo. Recorde-se que Feijoo colocou Luis Carrera como n\u00famero um da lista de Ourense contra a opini\u00e3o de Baltar, que nunca escondeu o seu descontentamento... Uma semana antes do in\u00edcio da campanha, Carrera foi demitido devido a um problema com os seus impostos. Mesmo assim, h\u00e1 que acrescentar mais um ingrediente \u00e0 \"receita de Baltar\". Foi ele que acompanhou Rajoy durante todos estes dias na sua prov\u00edncia, percorrendo os caminhos de terra, visitando as tabernas, recuperando um a um os votos de 2005. O pormenor das tabernas \u00e9 importante porque, segundo os coment\u00e1rios da imprensa, quando chegou a hora de partir, foi Baltar quem pagou todas as rondas.<br \/>\nComo \u00faltimo pormenor do desagrado de N\u00fa\u00f1ez Feijoo e da sua equipa, o v\u00eddeo que Genova colocou na Internet em que o candidato do PPdG s\u00f3 aparece durante dois segundos, encoberto pelo destaque total de Mariano Rajoy.<\/p>\n<p>\nFinalmente, o final da campanha do BNG, do meu ponto de vista, n\u00e3o foi t\u00e3o bom como se poderia desejar. Evidentemente, ningu\u00e9m esperava uns \u00faltimos dias t\u00e3o duros, com tantas acusa\u00e7\u00f5es que tiveram um apoio t\u00e3o forte de Madrid e de v\u00e1rios meios de comunica\u00e7\u00e3o galegos - penso que esta foi a legislatura em que os galegos come\u00e7aram a compreender a eterna queixa de catal\u00e3es e bascos de que o que os meios de comunica\u00e7\u00e3o estatais reflectem sobre as suas comunidades n\u00e3o tem, em muitas ocasi\u00f5es, nada a ver com a realidade.<\/p>\n<p>Sem excluir a possibilidade de todos estes ataques terem mobilizado a base do BNG, penso que a rea\u00e7\u00e3o de Quintana foi a de se colocar demasiado como v\u00edtima de uma campanha de ataques e de insistir demasiado na campanha suja que tem sido levada a cabo. Mesmo assim, h\u00e1 que reconhecer que \u00e9 muito dif\u00edcil contrariar a mensagem impl\u00edcita de todos estes alegados esc\u00e2ndalos - \"s\u00e3o todos iguais\" - que est\u00e1 a caminho de aumentar a absten\u00e7\u00e3o - pelo menos \u00e9 essa a perce\u00e7\u00e3o que se sente na rua.<\/p>\n<p>Dentro de 24 horas, as assembleias de voto ter\u00e3o encerrado e estaremos a fazer suposi\u00e7\u00f5es com os dados da aflu\u00eancia \u00e0s urnas e as sondagens que ser\u00e3o publicadas a partir das oito da noite. Eu estarei na sede da Proxectos em Ferrol. L\u00e1 estaremos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ontem \u00e0 noite, \u00e0s 00h00, a campanha galega de 2009 foi oficialmente encerrada. Finalmente, n\u00e3o houve surpresas medi\u00e1ticas de \u00faltima hora para acompanhar as que j\u00e1 tinham ocorrido durante os tr\u00eas dias anteriores.<\/p>","protected":false},"author":4,"featured_media":6532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Final de campa\u00f1a - Cecubo Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cecubogroup.com\/pt\/blog\/final-de-campana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Final de campa\u00f1a - Cecubo Group\" \/>\n<meta property=\"og:description\" content=\"Anoche, a las 00.00, se cerr\u00f3 oficialmente la campa\u00f1a gallega 2009. Finalmente, no hubo sorpresa medi\u00e1tica de \u00faltima hora que acompa\u00f1ara a las ya producidas durante los anteriores tres d\u00edas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cecubogroup.com\/pt\/blog\/final-de-campana\/\" \/>\n<meta property=\"og:site_name\" content=\"Cecubo Group\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-28T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-05T16:47:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.cecubogroup.com\/wp-content\/uploads\/2021\/01\/zapatero_amio-1508876892.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cecubogroup.com\/#website\",\"url\":\"https:\/\/www.cecubogroup.com\/\",\"name\":\"Cecubo Group\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cecubogroup.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#primaryimage\",\"inLanguage\":\"pt-PT\",\"url\":\"https:\/\/www.cecubogroup.com\/wp-content\/uploads\/2021\/01\/zapatero_amio-1508876892.jpg\",\"contentUrl\":\"https:\/\/www.cecubogroup.com\/wp-content\/uploads\/2021\/01\/zapatero_amio-1508876892.jpg\",\"caption\":\"zapatero_amio-1508876892.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#webpage\",\"url\":\"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/\",\"name\":\"Final de campa\\u00f1a - Cecubo Group\",\"isPartOf\":{\"@id\":\"https:\/\/www.cecubogroup.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#primaryimage\"},\"datePublished\":\"2009-02-28T00:00:00+00:00\",\"dateModified\":\"2021-04-05T16:47:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.cecubogroup.com\/#\/schema\/person\/760d350d20cf7baed1d099d37d22936f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/www.cecubogroup.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Final de campa\\u00f1a\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cecubogroup.com\/#\/schema\/person\/760d350d20cf7baed1d099d37d22936f\",\"name\":\"\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cecubogroup.com\/#personlogo\",\"inLanguage\":\"pt-PT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\"},\"url\":\"https:\/\/www.cecubogroup.com\/pt\/blog\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Final de campa\u00f1a - Cecubo Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cecubogroup.com\/pt\/blog\/final-de-campana\/","og_locale":"pt_PT","og_type":"article","og_title":"Final de campa\u00f1a - Cecubo Group","og_description":"Anoche, a las 00.00, se cerr\u00f3 oficialmente la campa\u00f1a gallega 2009. Finalmente, no hubo sorpresa medi\u00e1tica de \u00faltima hora que acompa\u00f1ara a las ya producidas durante los anteriores tres d\u00edas.","og_url":"https:\/\/www.cecubogroup.com\/pt\/blog\/final-de-campana\/","og_site_name":"Cecubo Group","article_published_time":"2009-02-28T00:00:00+00:00","article_modified_time":"2021-04-05T16:47:18+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.cecubogroup.com\/wp-content\/uploads\/2021\/01\/zapatero_amio-1508876892.jpg","twitter_misc":{"Escrito por":"","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cecubogroup.com\/#website","url":"https:\/\/www.cecubogroup.com\/","name":"Cecubo Group","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cecubogroup.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"ImageObject","@id":"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#primaryimage","inLanguage":"pt-PT","url":"https:\/\/www.cecubogroup.com\/wp-content\/uploads\/2021\/01\/zapatero_amio-1508876892.jpg","contentUrl":"https:\/\/www.cecubogroup.com\/wp-content\/uploads\/2021\/01\/zapatero_amio-1508876892.jpg","caption":"zapatero_amio-1508876892.jpg"},{"@type":"WebPage","@id":"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#webpage","url":"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/","name":"Final de campa\u00f1a - Cecubo Group","isPartOf":{"@id":"https:\/\/www.cecubogroup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#primaryimage"},"datePublished":"2009-02-28T00:00:00+00:00","dateModified":"2021-04-05T16:47:18+00:00","author":{"@id":"https:\/\/www.cecubogroup.com\/#\/schema\/person\/760d350d20cf7baed1d099d37d22936f"},"breadcrumb":{"@id":"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cecubogroup.com\/blog\/final-de-campana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cecubogroup.com\/"},{"@type":"ListItem","position":2,"name":"Final de campa\u00f1a"}]},{"@type":"Person","@id":"https:\/\/www.cecubogroup.com\/#\/schema\/person\/760d350d20cf7baed1d099d37d22936f","name":"","image":{"@type":"ImageObject","@id":"https:\/\/www.cecubogroup.com\/#personlogo","inLanguage":"pt-PT","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g"},"url":"https:\/\/www.cecubogroup.com\/pt\/blog\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/posts\/6277"}],"collection":[{"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/comments?post=6277"}],"version-history":[{"count":1,"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/posts\/6277\/revisions"}],"predecessor-version":[{"id":6793,"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/posts\/6277\/revisions\/6793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/media\/6532"}],"wp:attachment":[{"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/media?parent=6277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/categories?post=6277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cecubogroup.com\/pt\/wp-json\/wp\/v2\/tags?post=6277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}